{"id":1892,"date":"2020-10-16T16:16:36","date_gmt":"2020-10-16T16:16:36","guid":{"rendered":"https:\/\/ellok.org\/?post_type=portfolio&#038;p=1892"},"modified":"2024-10-16T16:18:51","modified_gmt":"2024-10-16T16:18:51","slug":"biosimilars-in-eu","status":"publish","type":"portfolio","link":"https:\/\/ellok.org\/en\/portfolio\/biosimilars-in-eu\/","title":{"rendered":"Biosimilars in EU"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"660\" src=\"https:\/\/ellok.org\/wp-content\/uploads\/2024\/10\/BIBL_Biosimilars-in-EU.jpg\" class=\"vc_single_image-img attachment-large\" alt=\"\" title=\"BIBL_Biosimilars-in-EU\" srcset=\"https:\/\/ellok.org\/wp-content\/uploads\/2024\/10\/BIBL_Biosimilars-in-EU.jpg 1000w, https:\/\/ellok.org\/wp-content\/uploads\/2024\/10\/BIBL_Biosimilars-in-EU-300x198.jpg 300w, https:\/\/ellok.org\/wp-content\/uploads\/2024\/10\/BIBL_Biosimilars-in-EU-768x507.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p class=\"w-post-elm post_title usg_post_title_1 has_text_color align_left entry-title color_link_inherit\"><strong>Biosimilars in EU<\/strong><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<blockquote><p>\n<a href=\"https:\/\/ellok.org\/wp-content\/uploads\/2024\/10\/19.-Biosimilars-in-EU.pdf\" target=\"_blank\" rel=\"noopener\">\u039a\u03b1\u03c4\u03b5\u03b2\u03ac\u03c3\u03c4\u03b5 \u03c4\u03bf \u03ad\u03bd\u03c4\u03c5\u03c0\u03bf<\/a>\n<\/p><\/blockquote>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Biosimilars in EU \u039a\u03b1\u03c4\u03b5\u03b2\u03ac\u03c3\u03c4\u03b5 \u03c4\u03bf \u03ad\u03bd\u03c4\u03c5\u03c0\u03bf","protected":false},"featured_media":1894,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","project-cat":[5],"class_list":["post-1892","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","project-cat-vivliothiki"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biosimilars in EU - \u0395\u039b\u039b\u039f\u039a \u2022 \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u039f\u03bc\u03bf\u03c3\u03c0\u03bf\u03bd\u03b4\u03af\u03b1 \u039a\u03b1\u03c1\u03ba\u03af\u03bd\u03bf\u03c5<\/title>\n<meta name=\"description\" content=\"\u0395\u039b\u039b\u039f\u039a - Biosimilars in EU\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ellok.org\/en\/portfolio\/biosimilars-in-eu\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biosimilars in EU - \u0395\u039b\u039b\u039f\u039a \u2022 \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u039f\u03bc\u03bf\u03c3\u03c0\u03bf\u03bd\u03b4\u03af\u03b1 \u039a\u03b1\u03c1\u03ba\u03af\u03bd\u03bf\u03c5\" \/>\n<meta property=\"og:description\" content=\"\u0395\u039b\u039b\u039f\u039a - Biosimilars in EU\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ellok.org\/en\/portfolio\/biosimilars-in-eu\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0395\u039b\u039b\u039f\u039a \u2022 \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u039f\u03bc\u03bf\u03c3\u03c0\u03bf\u03bd\u03b4\u03af\u03b1 \u039a\u03b1\u03c1\u03ba\u03af\u03bd\u03bf\u03c5\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ellok.org\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-16T16:18:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ellok.org\/wp-content\/uploads\/2024\/10\/BIBL_Biosimilars-in-EU.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"660\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EllokGr\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ellok.org\\\/portfolio\\\/biosimilars-in-eu\\\/\",\"url\":\"https:\\\/\\\/ellok.org\\\/portfolio\\\/biosimilars-in-eu\\\/\",\"name\":\"Biosimilars in EU - \u0395\u039b\u039b\u039f\u039a \u2022 \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u039f\u03bc\u03bf\u03c3\u03c0\u03bf\u03bd\u03b4\u03af\u03b1 \u039a\u03b1\u03c1\u03ba\u03af\u03bd\u03bf\u03c5\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ellok.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ellok.org\\\/portfolio\\\/biosimilars-in-eu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ellok.org\\\/portfolio\\\/biosimilars-in-eu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ellok.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/BIBL_Biosimilars-in-EU.jpg\",\"datePublished\":\"2020-10-16T16:16:36+00:00\",\"dateModified\":\"2024-10-16T16:18:51+00:00\",\"description\":\"\u0395\u039b\u039b\u039f\u039a - Biosimilars in EU\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ellok.org\\\/portfolio\\\/biosimilars-in-eu\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ellok.org\\\/portfolio\\\/biosimilars-in-eu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ellok.org\\\/portfolio\\\/biosimilars-in-eu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ellok.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/BIBL_Biosimilars-in-EU.jpg\",\"contentUrl\":\"https:\\\/\\\/ellok.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/BIBL_Biosimilars-in-EU.jpg\",\"width\":1000,\"height\":660},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ellok.org\\\/portfolio\\\/biosimilars-in-eu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\\\/\\\/ellok.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/ellok.org\\\/portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Biosimilars in EU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ellok.org\\\/#website\",\"url\":\"https:\\\/\\\/ellok.org\\\/\",\"name\":\"\u0395\u039b\u039b\u039f\u039a \u2022 \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u039f\u03bc\u03bf\u03c3\u03c0\u03bf\u03bd\u03b4\u03af\u03b1 \u039a\u03b1\u03c1\u03ba\u03af\u03bd\u03bf\u03c5\",\"description\":\"\u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u039f\u03bc\u03bf\u03c3\u03c0\u03bf\u03bd\u03b4\u03af\u03b1 \u039a\u03b1\u03c1\u03ba\u03af\u03bd\u03bf\u03c5\",\"publisher\":{\"@id\":\"https:\\\/\\\/ellok.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ellok.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ellok.org\\\/#organization\",\"name\":\"\u0395\u039b\u039b\u039f\u039a \u2022 \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u039f\u03bc\u03bf\u03c3\u03c0\u03bf\u03bd\u03b4\u03af\u03b1 \u039a\u03b1\u03c1\u03ba\u03af\u03bd\u03bf\u03c5\",\"url\":\"https:\\\/\\\/ellok.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ellok.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ellok.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ELLOK-Logo_GR.png\",\"contentUrl\":\"https:\\\/\\\/ellok.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ELLOK-Logo_GR.png\",\"width\":539,\"height\":185,\"caption\":\"\u0395\u039b\u039b\u039f\u039a \u2022 \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u039f\u03bc\u03bf\u03c3\u03c0\u03bf\u03bd\u03b4\u03af\u03b1 \u039a\u03b1\u03c1\u03ba\u03af\u03bd\u03bf\u03c5\"},\"image\":{\"@id\":\"https:\\\/\\\/ellok.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ellok.org\\\/\",\"https:\\\/\\\/x.com\\\/EllokGr\",\"https:\\\/\\\/www.instagram.com\\\/ellok_org\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCl-AYC1lxq7W03El1kRKSMA\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hellenic-cancer-federation\\\/?originalSubdomain=gr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biosimilars in EU - \u0395\u039b\u039b\u039f\u039a \u2022 \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u039f\u03bc\u03bf\u03c3\u03c0\u03bf\u03bd\u03b4\u03af\u03b1 \u039a\u03b1\u03c1\u03ba\u03af\u03bd\u03bf\u03c5","description":"\u0395\u039b\u039b\u039f\u039a - Biosimilars in EU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ellok.org\/en\/portfolio\/biosimilars-in-eu\/","og_locale":"en_GB","og_type":"article","og_title":"Biosimilars in EU - \u0395\u039b\u039b\u039f\u039a \u2022 \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u039f\u03bc\u03bf\u03c3\u03c0\u03bf\u03bd\u03b4\u03af\u03b1 \u039a\u03b1\u03c1\u03ba\u03af\u03bd\u03bf\u03c5","og_description":"\u0395\u039b\u039b\u039f\u039a - Biosimilars in EU","og_url":"https:\/\/ellok.org\/en\/portfolio\/biosimilars-in-eu\/","og_site_name":"\u0395\u039b\u039b\u039f\u039a \u2022 \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u039f\u03bc\u03bf\u03c3\u03c0\u03bf\u03bd\u03b4\u03af\u03b1 \u039a\u03b1\u03c1\u03ba\u03af\u03bd\u03bf\u03c5","article_publisher":"https:\/\/www.facebook.com\/ellok.org\/","article_modified_time":"2024-10-16T16:18:51+00:00","og_image":[{"width":1000,"height":660,"url":"https:\/\/ellok.org\/wp-content\/uploads\/2024\/10\/BIBL_Biosimilars-in-EU.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@EllokGr","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ellok.org\/portfolio\/biosimilars-in-eu\/","url":"https:\/\/ellok.org\/portfolio\/biosimilars-in-eu\/","name":"Biosimilars in EU - \u0395\u039b\u039b\u039f\u039a \u2022 \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u039f\u03bc\u03bf\u03c3\u03c0\u03bf\u03bd\u03b4\u03af\u03b1 \u039a\u03b1\u03c1\u03ba\u03af\u03bd\u03bf\u03c5","isPartOf":{"@id":"https:\/\/ellok.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ellok.org\/portfolio\/biosimilars-in-eu\/#primaryimage"},"image":{"@id":"https:\/\/ellok.org\/portfolio\/biosimilars-in-eu\/#primaryimage"},"thumbnailUrl":"https:\/\/ellok.org\/wp-content\/uploads\/2024\/10\/BIBL_Biosimilars-in-EU.jpg","datePublished":"2020-10-16T16:16:36+00:00","dateModified":"2024-10-16T16:18:51+00:00","description":"\u0395\u039b\u039b\u039f\u039a - Biosimilars in EU","breadcrumb":{"@id":"https:\/\/ellok.org\/portfolio\/biosimilars-in-eu\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ellok.org\/portfolio\/biosimilars-in-eu\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ellok.org\/portfolio\/biosimilars-in-eu\/#primaryimage","url":"https:\/\/ellok.org\/wp-content\/uploads\/2024\/10\/BIBL_Biosimilars-in-EU.jpg","contentUrl":"https:\/\/ellok.org\/wp-content\/uploads\/2024\/10\/BIBL_Biosimilars-in-EU.jpg","width":1000,"height":660},{"@type":"BreadcrumbList","@id":"https:\/\/ellok.org\/portfolio\/biosimilars-in-eu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/ellok.org\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/ellok.org\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Biosimilars in EU"}]},{"@type":"WebSite","@id":"https:\/\/ellok.org\/#website","url":"https:\/\/ellok.org\/","name":"\u0395\u039b\u039b\u039f\u039a \u2022 \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u039f\u03bc\u03bf\u03c3\u03c0\u03bf\u03bd\u03b4\u03af\u03b1 \u039a\u03b1\u03c1\u03ba\u03af\u03bd\u03bf\u03c5","description":"Hellenic Cancer Federation","publisher":{"@id":"https:\/\/ellok.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ellok.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/ellok.org\/#organization","name":"\u0395\u039b\u039b\u039f\u039a \u2022 \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u039f\u03bc\u03bf\u03c3\u03c0\u03bf\u03bd\u03b4\u03af\u03b1 \u039a\u03b1\u03c1\u03ba\u03af\u03bd\u03bf\u03c5","url":"https:\/\/ellok.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ellok.org\/#\/schema\/logo\/image\/","url":"https:\/\/ellok.org\/wp-content\/uploads\/2024\/05\/ELLOK-Logo_GR.png","contentUrl":"https:\/\/ellok.org\/wp-content\/uploads\/2024\/05\/ELLOK-Logo_GR.png","width":539,"height":185,"caption":"\u0395\u039b\u039b\u039f\u039a \u2022 \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u039f\u03bc\u03bf\u03c3\u03c0\u03bf\u03bd\u03b4\u03af\u03b1 \u039a\u03b1\u03c1\u03ba\u03af\u03bd\u03bf\u03c5"},"image":{"@id":"https:\/\/ellok.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ellok.org\/","https:\/\/x.com\/EllokGr","https:\/\/www.instagram.com\/ellok_org\/","https:\/\/www.youtube.com\/channel\/UCl-AYC1lxq7W03El1kRKSMA","https:\/\/www.linkedin.com\/company\/hellenic-cancer-federation\/?originalSubdomain=gr"]}]}},"_links":{"self":[{"href":"https:\/\/ellok.org\/en\/wp-json\/wp\/v2\/portfolio\/1892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellok.org\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/ellok.org\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/ellok.org\/en\/wp-json\/wp\/v2\/comments?post=1892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellok.org\/en\/wp-json\/wp\/v2\/media\/1894"}],"wp:attachment":[{"href":"https:\/\/ellok.org\/en\/wp-json\/wp\/v2\/media?parent=1892"}],"wp:term":[{"taxonomy":"project-cat","embeddable":true,"href":"https:\/\/ellok.org\/en\/wp-json\/wp\/v2\/project-cat?post=1892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}